{
    "id": 39827,
    "date": "2026-06-19T05:11:13",
    "date_gmt": "2026-06-19T02:11:13",
    "guid": {
        "rendered": "https:\/\/olestorebh.com\/?post_type=product&#038;p=39827"
    },
    "modified": "2026-06-19T05:12:25",
    "modified_gmt": "2026-06-19T02:12:25",
    "slug": "lyon-away-2026-27-player-edition",
    "status": "publish",
    "type": "product",
    "link": "https:\/\/olestorebh.com\/en\/product\/lyon-away-2026-27-player-edition\/",
    "title": {
        "rendered": "Lyon Away 2026-27 Player Edition"
    },
    "content": {
        "rendered": "<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-18224\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/06\/ssfff-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/06\/ssfff-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/06\/ssfff-1024x1024.jpg 1024w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/06\/ssfff-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/06\/ssfff-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/06\/ssfff-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/06\/ssfff-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/06\/ssfff-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/06\/ssfff.jpg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-18225\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/06\/ddd-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/06\/ddd-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/06\/ddd-1024x1024.jpg 1024w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/06\/ddd-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/06\/ddd-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/06\/ddd-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/06\/ddd-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/06\/ddd-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/06\/ddd.jpg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>",
        "protected": false
    },
    "excerpt": {
        "rendered": "<p>Pre-Order \u0637\u0644\u0628 \u0645\u0633\u0628\u0642<\/p>",
        "protected": false
    },
    "featured_media": 39836,
    "comment_status": "open",
    "ping_status": "closed",
    "template": "",
    "meta": {
        "_joinchat": []
    },
    "product_brand": [],
    "product_cat": [
        121
    ],
    "product_tag": [],
    "class_list": {
        "0": "post-39827",
        "1": "product",
        "2": "type-product",
        "3": "status-publish",
        "4": "has-post-thumbnail",
        "6": "product_cat-pre-order-player-edition",
        "8": "first",
        "9": "onbackorder",
        "10": "shipping-taxable",
        "11": "purchasable",
        "12": "product-type-variable"
    },
    "_links": {
        "self": [
            {
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/product\/39827",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/product"
            }
        ],
        "about": [
            {
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/types\/product"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/comments?post=39827"
            }
        ],
        "version-history": [
            {
                "count": 1,
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/product\/39827\/revisions"
            }
        ],
        "predecessor-version": [
            {
                "id": 39837,
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/product\/39827\/revisions\/39837"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/media\/39836"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/media?parent=39827"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "product_brand",
                "embeddable": true,
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/product_brand?post=39827"
            },
            {
                "taxonomy": "product_cat",
                "embeddable": true,
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/product_cat?post=39827"
            },
            {
                "taxonomy": "product_tag",
                "embeddable": true,
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/product_tag?post=39827"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}