{
    "id": 39671,
    "date": "2026-06-15T01:05:28",
    "date_gmt": "2026-06-14T22:05:28",
    "guid": {
        "rendered": "https:\/\/olestorebh.com\/?post_type=product&#038;p=39671"
    },
    "modified": "2026-06-15T01:06:35",
    "modified_gmt": "2026-06-14T22:06:35",
    "slug": "jordan-third-away-2026-27-player-edition",
    "status": "publish",
    "type": "product",
    "link": "https:\/\/olestorebh.com\/en\/product\/jordan-third-away-2026-27-player-edition\/",
    "title": {
        "rendered": "Jordan Third Away 2026-27 Player Edition"
    },
    "content": {
        "rendered": "<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15344\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/1-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/1-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/1-1024x1024.jpg 1024w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/1-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/1-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/1-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/1-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/1-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/1.jpg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15345\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/12-1-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/12-1-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/12-1-1024x1024.jpg 1024w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/12-1-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/12-1-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/12-1-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/12-1-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/12-1-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/12-1.jpg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15280\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/DSAA-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/DSAA-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/DSAA-1024x1024.jpg 1024w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/DSAA-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/DSAA-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/DSAA-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/DSAA-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/DSAA-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/DSAA.jpg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15281\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/WSS-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/WSS-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/WSS-1024x1024.jpg 1024w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/WSS-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/WSS-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/WSS-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/WSS-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/WSS-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/WSS.jpg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>",
        "protected": false
    },
    "excerpt": {
        "rendered": "<p>Pre-Order \u0637\u0644\u0628 \u0645\u0633\u0628\u0642<\/p>",
        "protected": false
    },
    "featured_media": 39680,
    "comment_status": "open",
    "ping_status": "closed",
    "template": "",
    "meta": {
        "_joinchat": []
    },
    "product_brand": [],
    "product_cat": [
        142
    ],
    "product_tag": [],
    "class_list": {
        "0": "post-39671",
        "1": "product",
        "2": "type-product",
        "3": "status-publish",
        "4": "has-post-thumbnail",
        "6": "product_cat-pre-order-world-cup-player-edition",
        "8": "first",
        "9": "onbackorder",
        "10": "shipping-taxable",
        "11": "purchasable",
        "12": "product-type-variable"
    },
    "_links": {
        "self": [
            {
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/product\/39671",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/product"
            }
        ],
        "about": [
            {
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/types\/product"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/comments?post=39671"
            }
        ],
        "version-history": [
            {
                "count": 1,
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/product\/39671\/revisions"
            }
        ],
        "predecessor-version": [
            {
                "id": 39681,
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/product\/39671\/revisions\/39681"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/media\/39680"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/media?parent=39671"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "product_brand",
                "embeddable": true,
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/product_brand?post=39671"
            },
            {
                "taxonomy": "product_cat",
                "embeddable": true,
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/product_cat?post=39671"
            },
            {
                "taxonomy": "product_tag",
                "embeddable": true,
                "href": "https:\/\/olestorebh.com\/en\/wp-json\/wp\/v2\/product_tag?post=39671"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}