{"id":40433,"date":"2026-07-14T23:50:06","date_gmt":"2026-07-14T20:50:06","guid":{"rendered":"https:\/\/olestorebh.com\/?post_type=product&#038;p=40433"},"modified":"2026-07-14T23:52:30","modified_gmt":"2026-07-14T20:52:30","slug":"barcelona-home-2026-27-ultra-fan-edition","status":"publish","type":"product","link":"https:\/\/olestorebh.com\/ar\/product\/barcelona-home-2026-27-ultra-fan-edition\/","title":{"rendered":"Barcelona Home 2026-27 Ultra Fan Edition"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/ssdf-1-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" class=\"alignnone size-medium wp-image-17997\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/ssdf-1-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/ssdf-1-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/ssdf-1-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/ssdf-1-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/ssdf-1-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/ssdf-1-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/ssdf-1.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/ssff-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" class=\"alignnone size-medium wp-image-17998\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/ssff-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/ssff-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/ssff-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/ssff-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/ssff-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/ssff-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/ssff.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-5-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" class=\"alignnone size-medium wp-image-17469\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-5-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-5-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-5-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-5-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-5-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-5-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-5.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/GFF-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" class=\"alignnone size-medium wp-image-17470\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/GFF-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/GFF-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/GFF-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/GFF-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/GFF-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/GFF-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/GFF.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/fsww-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" class=\"alignnone size-medium wp-image-17383\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/fsww-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/fsww-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/fsww-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/fsww-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/fsww-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/fsww-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/fsww.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-vds-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" class=\"alignnone size-medium wp-image-17384\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-vds-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-vds-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-vds-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-vds-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-vds-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-vds-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-vds.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/sgg-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" class=\"alignnone size-medium wp-image-17374\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/sgg-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/sgg-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/sgg-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/sgg-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/sgg-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/sgg-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/sgg.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-fd-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" class=\"alignnone size-medium wp-image-17375\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-fd-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-fd-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-fd-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-fd-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-fd-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-fd-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-fd.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Pre-Order \u0637\u0644\u0628 \u0645\u0633\u0628\u0642<\/p>","protected":false},"featured_media":40442,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[120],"product_tag":[],"class_list":{"0":"post-40433","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pre-order-fan-edition","8":"first","9":"onbackorder","10":"shipping-taxable","11":"purchasable","12":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product\/40433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/comments?post=40433"}],"version-history":[{"count":1,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product\/40433\/revisions"}],"predecessor-version":[{"id":40443,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product\/40433\/revisions\/40443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/media\/40442"}],"wp:attachment":[{"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/media?parent=40433"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product_brand?post=40433"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product_cat?post=40433"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product_tag?post=40433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}