{"id":39869,"date":"2026-06-19T07:03:52","date_gmt":"2026-06-19T04:03:52","guid":{"rendered":"https:\/\/olestorebh.com\/?post_type=product&#038;p=39869"},"modified":"2026-06-19T07:06:04","modified_gmt":"2026-06-19T04:06:04","slug":"ferrari-2025-f1-edition-5","status":"publish","type":"product","link":"https:\/\/olestorebh.com\/ar\/product\/ferrari-2025-f1-edition-5\/","title":{"rendered":"Ferrari 2025 F1 Edition"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15271\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/SD-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/SD-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/SD-1024x1024.jpg 1024w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/SD-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/SD-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/SD-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/SD-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/SD-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/SD.jpg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15272\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/111-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/111-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/111-1024x1024.jpg 1024w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/111-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/111-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/111-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/111-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/111-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/02\/111.jpg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":29312,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[116],"product_tag":[],"class_list":{"0":"post-39869","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-outlet","8":"first","9":"instock","10":"sale","11":"shipping-taxable","12":"purchasable","13":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product\/39869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/comments?post=39869"}],"version-history":[{"count":1,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product\/39869\/revisions"}],"predecessor-version":[{"id":39878,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product\/39869\/revisions\/39878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/media\/29312"}],"wp:attachment":[{"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/media?parent=39869"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product_brand?post=39869"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product_cat?post=39869"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product_tag?post=39869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}