{"id":39703,"date":"2026-06-16T03:18:15","date_gmt":"2026-06-16T00:18:15","guid":{"rendered":"https:\/\/olestorebh.com\/?post_type=product&#038;p=39703"},"modified":"2026-06-16T03:19:31","modified_gmt":"2026-06-16T00:19:31","slug":"liverpool-home-2026-27-player-kids-suit-edition","status":"publish","type":"product","link":"https:\/\/olestorebh.com\/ar\/product\/liverpool-home-2026-27-player-kids-suit-edition\/","title":{"rendered":"Liverpool Home 2026-27 Player Kids Suit Edition"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-19754\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/07\/image7-3-300x300.jpeg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/07\/image7-3-300x300.jpeg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/07\/image7-3-150x150.jpeg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/07\/image7-3-768x768.jpeg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/07\/image7-3-12x12.jpeg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/07\/image7-3-600x600.jpeg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/07\/image7-3-148x148.jpeg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/07\/image7-3.jpeg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-19755\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/07\/image8-4-300x300.jpeg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/07\/image8-4-300x300.jpeg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/07\/image8-4-150x150.jpeg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/07\/image8-4-768x768.jpeg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/07\/image8-4-12x12.jpeg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/07\/image8-4-600x600.jpeg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/07\/image8-4-148x148.jpeg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/07\/image8-4.jpeg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-17941\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-3ss-1-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-3ss-1-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-3ss-1-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-3ss-1-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-3ss-1-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-3ss-1-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-3ss-1-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-3ss-1.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-17942\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/saa-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/saa-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/saa-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/saa-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/saa-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/saa-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/saa-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/saa.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-17930\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/wdd-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/wdd-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/wdd-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/wdd-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/wdd-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/wdd-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/wdd-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/wdd.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-17931\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/sss-1-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/sss-1-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/sss-1-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/sss-1-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/sss-1-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/sss-1-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/sss-1-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/sss-1.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-17886\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-3-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-3-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-3-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-3-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-3-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-3-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-3-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/Untitled-3.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-17887\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/df-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/df-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/df-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/df-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/df-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/df-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/df-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/df.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-17263\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/d-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/d-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/d-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/d-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/d-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/d-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/d-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/d.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-17264\" src=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/cdff-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/cdff-300x300.jpg 300w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/cdff-150x150.jpg 150w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/cdff-768x768.jpg 768w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/cdff-12x12.jpg 12w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/cdff-600x600.jpg 600w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/cdff-148x148.jpg 148w, https:\/\/olestorebh.com\/wp-content\/uploads\/2025\/05\/cdff.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Pre-Order \u0637\u0644\u0628 \u0645\u0633\u0628\u0642<\/p>","protected":false},"featured_media":39712,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[154],"product_tag":[],"class_list":{"0":"post-39703","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pre-order-player-kids-suits","8":"first","9":"onbackorder","10":"shipping-taxable","11":"purchasable","12":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product\/39703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/comments?post=39703"}],"version-history":[{"count":1,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product\/39703\/revisions"}],"predecessor-version":[{"id":39713,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product\/39703\/revisions\/39713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/media\/39712"}],"wp:attachment":[{"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/media?parent=39703"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product_brand?post=39703"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product_cat?post=39703"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/olestorebh.com\/ar\/wp-json\/wp\/v2\/product_tag?post=39703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}